{"id":1129,"date":"2024-02-06T12:16:47","date_gmt":"2024-02-06T11:16:47","guid":{"rendered":"https:\/\/wynelabel.eu\/site-notice\/"},"modified":"2024-08-14T13:58:27","modified_gmt":"2024-08-14T11:58:27","slug":"site-notice","status":"publish","type":"page","link":"https:\/\/wynelabel.eu\/it\/site-notice\/","title":{"rendered":"Impronta"},"content":{"rendered":"<div class=\"gb-container gb-container-42d84b2c gbp-section__inner\">\n\n<h1 class=\"wp-block-heading\">Impronta<\/h1>\n\n\n\n<p>grieblmedia GmbH<br\/>Lenderstra\u00dfe 10<br\/>77880 Sasbach<\/p>\n\n\n\n<p>Registro delle imprese: HRB 702080<br\/>Tribunale: Tribunale locale di Mannheim<\/p>\n\n\n\n<p><strong>Rappresentato da:<\/strong> <br\/>Oliver Griebl<br\/>Matthias Griebl<\/p>\n\n\n\n<p><strong>Contattaci<\/strong><\/p>\n\n\n\n<p>Telefono: +49(0)78418392661<br\/>E-mail: info@grieblmedia.de<\/p>\n\n\n\n<p><strong>ID dell&#8217;imposta sulle vendite<\/strong><\/p>\n\n\n\n<p>Numero di identificazione dell&#8217;imposta sul valore aggiunto ai sensi del \u00a7 27 a della legge sull&#8217;imposta sul valore aggiunto: DE252850240<\/p>\n\n\n\n<p><strong>Responsabile editoriale<\/strong><\/p>\n\n\n\n<p>Oliver Griebl<br\/>Lenderstra\u00dfe 10<br\/>77880 Sasbach<\/p>\n\n\n\n<p><strong>Risoluzione delle controversie nell&#8217;UE<\/strong><\/p>\n\n\n\n<p>La Commissione europea mette a disposizione una piattaforma per la risoluzione delle controversie online (OS): <a href=\"https:\/\/ec.europa.eu\/consumers\/odr\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/ec.europa.eu\/consumers\/odr\/.<\/a> Puoi trovare il nostro indirizzo e-mail nell&#8217;avviso legale di cui sopra.<\/p>\n\n\n\n<p><strong>Centro di risoluzione delle controversie dei consumatori\/ arbitrato universale<\/strong><\/p>\n\n\n\n<p>Non siamo disposti o obbligati a partecipare a procedure di risoluzione delle controversie davanti a un collegio arbitrale dei consumatori.<\/p>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Impronta grieblmedia GmbHLenderstra\u00dfe 1077880 Sasbach Registro delle imprese: HRB 702080Tribunale: Tribunale locale di Mannheim Rappresentato da: Oliver GrieblMatthias Griebl Contattaci Telefono: +49(0)78418392661E-mail: info@grieblmedia.de ID dell&#8217;imposta sulle vendite Numero di identificazione dell&#8217;imposta sul valore aggiunto ai sensi del \u00a7 27 a della legge sull&#8217;imposta sul valore aggiunto: DE252850240 Responsabile editoriale Oliver GrieblLenderstra\u00dfe 1077880 Sasbach Risoluzione delle &#8230; <a title=\"Impronta\" class=\"read-more\" href=\"https:\/\/wynelabel.eu\/it\/site-notice\/\" aria-label=\"Per saperne di pi\u00f9 su Impronta\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-1129","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/pages\/1129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/comments?post=1129"}],"version-history":[{"count":3,"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/pages\/1129\/revisions"}],"predecessor-version":[{"id":1152,"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/pages\/1129\/revisions\/1152"}],"wp:attachment":[{"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/media?parent=1129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}