{"id":1383,"date":"2024-11-06T12:48:26","date_gmt":"2024-11-06T11:48:26","guid":{"rendered":"https:\/\/wynelabel.eu\/come-posso-creare-unetichetta-elettronica-per-il-vino-con-wynelabel\/"},"modified":"2024-11-08T20:21:46","modified_gmt":"2024-11-08T19:21:46","slug":"come-posso-creare-unetichetta-elettronica-per-il-vino-con-wynelabel","status":"publish","type":"post","link":"https:\/\/wynelabel.eu\/it\/come-posso-creare-unetichetta-elettronica-per-il-vino-con-wynelabel\/","title":{"rendered":"Come posso creare un&#8217;etichetta elettronica per il vino con Wynelabel?"},"content":{"rendered":"\n<p>Clicchi sul pulsante &#8220;E-LABELS&#8221; nella dashboard di Wynelabel. Questo la porta all&#8217;elenco delle sue etichette elettroniche. Clicchi sul pulsante arancione con il segno pi\u00f9 per creare una nuova etichetta elettronica.  <\/p>\n<div class=\"gb-container gb-container-a390d774\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"750\" src=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/\/grafik-1200x750.png\" alt=\"\" class=\"wp-image-1258\" srcset=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-1200x750.png 1200w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-600x375.png 600w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-768x480.png 768w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik.png 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<\/div>\n<p>Il nome della sua cantina \u00e8 preassegnato dall&#8217;indirizzo di fatturazione che ha inserito, ma pu\u00f2 inserire qualsiasi nome desideri. Il nome della cantina viene visualizzato nella parte superiore dell&#8217;etichetta elettronica per facilitare l&#8217;identificazione del vino da parte dell&#8217;acquirente. <\/p>\n\n<p>Quando compila tutti i campi informativi, tenga presente che la legge stabilisce che nessuna informazione pubblicitaria pu\u00f2 comparire sull&#8217;etichetta elettronica. Resta da vedere come questo verr\u00e0 interpretato esattamente nella giurisprudenza. <\/p>\n\n<p>Compili i campi della scheda &#8220;INFO&#8221; come mostrato nell&#8217;esempio seguente:<\/p>\n<div class=\"gb-container gb-container-08a44bf9\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"750\" src=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/\/grafik-1-1200x750.png\" alt=\"\" class=\"wp-image-1264\" srcset=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-1-1200x750.png 1200w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-1-600x375.png 600w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-1-768x480.png 768w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-1.png 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<\/div>\n<p>Nella fase successiva, nella scheda &#8220;ELENCO INGREDIENTI&#8221;, clicchi sul pulsante &#8220;MODIFICA ELENCO INGREDIENTI&#8221;.<\/p>\n<div class=\"gb-container gb-container-d3613aa7\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"750\" src=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/\/grafik-2-1200x750.png\" alt=\"\" class=\"wp-image-1270\" srcset=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-2-1200x750.png 1200w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-2-600x375.png 600w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-2-768x480.png 768w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-2.png 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<\/div>\n<p>Si apre quindi la finestra con l&#8217;editor dell&#8217;elenco degli ingredienti. Nel caso pi\u00f9 semplice di un vino classico, ad esempio, i seguenti ingredienti devono essere inclusi nell&#8217;elenco degli ingredienti: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Uva<\/li>\n\n\n\n<li>Saccarosio (solo se aggiunto al vino)<\/li>\n\n\n\n<li>Anidride solforosa (solo se aggiunta al vino)<\/li>\n<\/ul>\n\n<p>Nell&#8217;elenco di destra, clicchi sull&#8217;icona con l&#8217;elenco\/il segno pi\u00f9 a sinistra dell&#8217;ingrediente &#8220;Uva&#8221;, in modo che l'&#8221;Uva&#8221; venga aggiunta all&#8217;elenco di sinistra.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"40\" height=\"45\" src=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-4.png\" alt=\"\" class=\"wp-image-1282\"\/><\/figure>\n\n<p>Se presente nel suo vino, aggiunga l&#8217;ingrediente &#8220;saccarosio&#8221; all&#8217;elenco degli ingredienti nello stesso modo.<\/p>\n\n<p>Se presente nel suo vino, aggiunga anche l&#8217;ingrediente &#8220;anidride solforosa&#8221;. Per trovare un ingrediente specifico, inserisca il termine nel campo di ricerca a destra, sopra l&#8217;elenco degli ingredienti. \u00c8 sufficiente inserire &#8220;schw&#8221; per filtrare l&#8217;elenco degli ingredienti in modo che appaia &#8220;anidride solforosa&#8221;. Quindi clicchi sull&#8217;icona con l&#8217;elenco\/segno pi\u00f9 a sinistra dell&#8217;ingrediente &#8220;anidride solforosa&#8221;.   <\/p>\n\n<p>L&#8217;ingrediente &#8220;biossido di zolfo&#8221; viene aggiunto automaticamente sotto la classe di ingredienti corrispondente &#8220;conservanti e antiossidanti&#8221; e contrassegnato come allergene.<\/p>\n<div class=\"gb-container gb-container-36f14edf\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"750\" src=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/\/grafik-5-1200x750.png\" alt=\"\" class=\"wp-image-1288\" srcset=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-5-1200x750.png 1200w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-5-600x375.png 600w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-5-768x480.png 768w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-5.png 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<\/div>\n<p>Ora clicchi sul pulsante &#8220;SALVA&#8221; nell&#8217;angolo in alto a destra per salvare l&#8217;elenco degli ingredienti. Questo creer\u00e0 e salver\u00e0 automaticamente le traduzioni dell&#8217;elenco degli ingredienti per tutte le altre lingue. <\/p>\n<div class=\"gb-container gb-container-9b35948b\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"756\" src=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/\/grafik-11-1200x756.png\" alt=\"\" class=\"wp-image-1330\" srcset=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-11-1200x756.png 1200w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-11-600x378.png 600w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-11-768x484.png 768w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-11.png 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<\/div>\n<p>Ora passi alla scheda &#8220;TABELLA NUTRIZIONE&#8221; per inserire il valore calorico e le proporzioni di carboidrati e zuccheri. Attivi anche la casella &#8220;Contiene piccole quantit\u00e0 di grassi, acidi grassi saturi, proteine e sale&#8221; se il suo vino non contiene altri ingredienti oltre il limite.<\/p>\n<div class=\"gb-container gb-container-895dc872\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"750\" src=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/\/grafik-6-1200x750.png\" alt=\"\" class=\"wp-image-1294\" srcset=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-6-1200x750.png 1200w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-6-600x375.png 600w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-6-768x480.png 768w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-6.png 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<\/div>\n<p>Se desidera visualizzare un&#8217;immagine della bottiglia e\/o un sigillo informativo sull&#8217;etichetta elettronica, passi alla scheda &#8220;IMMAGINI&#8221;. Si prega di notare che non \u00e8 consentito alcun contenuto di marketing sull&#8217;etichetta elettronica stessa. Se l&#8217;immagine di una bottiglia sia legalmente consentita \u00e8 ancora controverso. Se vuole andare sul sicuro, non aggiunga l&#8217;immagine della bottiglia.   <\/p>\n\n<p>Clicchi sul pulsante corrispondente &#8220;UPLOAD&#8221; per selezionare un file per l&#8217;immagine della bottiglia o un sigillo informativo dal suo computer. Sono ammessi i file con estensione .jpg, .png, .gif o .webp. La dimensione massima del file \u00e8 di 20 megabyte.<\/p>\n\n<p>Ha delle foto con informazioni sul riciclaggio? Le carichi qui come sigilli informativi. Pu\u00f2 cambiare l&#8217;ordine delle immagini dei sigilli informativi trascinandole con il mouse.  <\/p>\n<div class=\"gb-container gb-container-54d06184\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"750\" src=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/\/grafik-7-1200x750.png\" alt=\"\" class=\"wp-image-1300\" srcset=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-7-1200x750.png 1200w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-7-600x375.png 600w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-7-768x480.png 768w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-7.png 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<\/div>\n<p>Ora passi all&#8217;ultima scheda &#8220;E_LABEL&#8221; per verificare e pubblicare l&#8217;etichetta elettronica e per scaricare il codice QR.<\/p>\n\n<p>Se desidera pre-pubblicare l&#8217;e-label, ad esempio se non sono ancora disponibili tutti i dati di analisi per l&#8217;e-label, pubblichi l&#8217;e-label con l&#8217;opzione &#8220;In preparazione&#8221;. Questa opzione deve essere disattivata manualmente e l&#8217;e-label deve essere aggiornata prima della consegna della merce, una volta aggiunti i dati di analisi. <\/p>\n\n<p>Cliccando sul pulsante arancione &#8220;PUBBLICA E-LABEL&#8221; in alto a destra, verr\u00e0 prima portato al pop-up di conferma, dove le verranno fornite le istruzioni e la possibilit\u00e0 di far tradurre automaticamente i dati inseriti prima della pubblicazione.<\/p>\n\n<p>Deve creare un&#8217;impronta per l&#8217;etichetta elettronica prima di pubblicarla. Pu\u00f2 farlo tramite la dashboard o il profilo Wynelabel. Solo allora il pulsante &#8220;PUBBLICA E-LABEL&#8221; sar\u00e0 attivato e la pubblicazione sar\u00e0 possibile.  <\/p>\n<div class=\"gb-container gb-container-6158a419\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1176\" height=\"900\" src=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/\/grafik-8-1176x900.png\" alt=\"\" class=\"wp-image-1306\" srcset=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-8-1176x900.png 1176w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-8-600x459.png 600w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-8-768x588.png 768w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-8.png 1280w\" sizes=\"auto, (max-width: 1176px) 100vw, 1176px\" \/><\/figure>\n\n<\/div>\n<p>Non appena ha pubblicato l&#8217;etichetta elettronica, una voce corrispondente appare nell&#8217;elenco della cronologia a destra. Cliccando sul pulsante verde scuro del telefono cellulare con il numero consecutivo, pu\u00f2 verificare quale etichetta elettronica \u00e8 stata pubblicata con quali dati e quando. <\/p>\n\n<p>Cliccando sul pulsante verde chiaro &#8220;DEPUBBLICA E-LABEL&#8221;, pu\u00f2 depubblicare l&#8217;E-LABEL in modo che il codice QR porti a una pagina di errore invece che all&#8217;E-Label.<\/p>\n<div class=\"gb-container gb-container-b8b8e823\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1176\" height=\"900\" src=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/\/grafik-9-1176x900.png\" alt=\"\" class=\"wp-image-1312\" srcset=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-9-1176x900.png 1176w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-9-600x459.png 600w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-9-768x588.png 768w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-9.png 1280w\" sizes=\"auto, (max-width: 1176px) 100vw, 1176px\" \/><\/figure>\n\n<\/div><div class=\"gb-container gb-container-d797d634\">\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"756\" src=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/\/grafik-10-1200x756.png\" alt=\"\" class=\"wp-image-1318\" srcset=\"https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-10-1200x756.png 1200w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-10-600x378.png 600w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-10-768x484.png 768w, https:\/\/wynelabel.eu\/wp-content\/uploads\/grafik-10.png 1280w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n<\/div>\n<p>Come ultimo passo, scarichi il codice QR per l&#8217;etichetta elettronica che ha appena pubblicato, cliccando su uno dei due pulsanti di download con la freccia rivolta verso il basso. Ha la possibilit\u00e0 di scegliere tra un download come file bitmap (PNG) o come file vettoriale (SVG). <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Clicchi sul pulsante &#8220;E-LABELS&#8221; nella dashboard di Wynelabel. Questo la porta all&#8217;elenco delle sue etichette elettroniche. Clicchi sul pulsante arancione con il segno pi\u00f9 per creare una nuova etichetta elettronica. Il nome della sua cantina \u00e8 preassegnato dall&#8217;indirizzo di fatturazione che ha inserito, ma pu\u00f2 inserire qualsiasi nome desideri. Il nome della cantina viene visualizzato &#8230; <a title=\"Come posso creare un&#8217;etichetta elettronica per il vino con Wynelabel?\" class=\"read-more\" href=\"https:\/\/wynelabel.eu\/it\/come-posso-creare-unetichetta-elettronica-per-il-vino-con-wynelabel\/\" aria-label=\"Per saperne di pi\u00f9 su Come posso creare un&#8217;etichetta elettronica per il vino con Wynelabel?\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-1383","post","type-post","status-publish","format-standard","hentry","category-suggerimenti-e-trucchi"],"_links":{"self":[{"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/posts\/1383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/comments?post=1383"}],"version-history":[{"count":1,"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/posts\/1383\/revisions"}],"predecessor-version":[{"id":1384,"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/posts\/1383\/revisions\/1384"}],"wp:attachment":[{"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/media?parent=1383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/categories?post=1383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wynelabel.eu\/it\/wp-json\/wp\/v2\/tags?post=1383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}